{"id":1508,"date":"2022-11-11T02:56:27","date_gmt":"2022-11-11T02:56:27","guid":{"rendered":"https:\/\/www.tcm-vet.com\/?p=1508"},"modified":"2023-04-18T17:14:36","modified_gmt":"2023-04-18T17:14:36","slug":"medicamentos-para-tratar-tumores-y-canceres-en-perros","status":"publish","type":"post","link":"https:\/\/www.tcm-vet.com\/es\/drugs-for-treating-dog-tumors-and-cancers\/","title":{"rendered":"F\u00e1rmacos para el tratamiento de tumores y c\u00e1nceres caninos"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Los f\u00e1rmacos son una parte importante del tratamiento de los tumores y c\u00e1nceres caninos. Sin ellos, muchos tratamientos no ser\u00edan posibles. Los f\u00e1rmacos se utilizan para tratar directamente el tumor, as\u00ed como para tratar los efectos secundarios de los tratamientos. Los antibi\u00f3ticos se utilizan para tratar las infecciones, y los f\u00e1rmacos contra las n\u00e1useas se utilizan para prevenir y tratar las n\u00e1useas y los v\u00f3mitos. Los analg\u00e9sicos se utilizan para controlar el dolor y los antiinflamatorios para reducir la inflamaci\u00f3n. Muchos tratamientos s\u00f3lo son posibles con f\u00e1rmacos. Entre ellos se incluyen la quimioterapia, la radioterapia y la inmunoterapia. Son tratamientos que s\u00f3lo pueden administrarse con f\u00e1rmacos. Tambi\u00e9n hay otros tratamientos que pueden realizarse con f\u00e1rmacos. Por ejemplo, la terapia hormonal, la terapia dirigida y la terapia biol\u00f3gica. Estas terapias pueden utilizarse junto con otros tratamientos para proporcionar el tratamiento m\u00e1s eficaz posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existen varios f\u00e1rmacos eficaces en el tratamiento de tumores y c\u00e1nceres caninos. Los m\u00e1s comunes son los f\u00e1rmacos quimioter\u00e1picos, que act\u00faan eliminando las c\u00e9lulas cancerosas. Otros f\u00e1rmacos que pueden utilizarse son la radioterapia, la inmunoterapia y la terapia dirigida. La quimioterapia es el tratamiento m\u00e1s com\u00fan de los tumores y c\u00e1nceres caninos. Los f\u00e1rmacos quimioter\u00e1picos destruyen las c\u00e9lulas cancerosas. Los f\u00e1rmacos de quimioterapia m\u00e1s utilizados para tratar los tumores y c\u00e1nceres caninos son el carboplatino, la doxorrubicina y la vincristina. El carboplatino es un f\u00e1rmaco de quimioterapia a base de platino que act\u00faa interfiriendo en la capacidad de divisi\u00f3n de las c\u00e9lulas cancerosas. La doxorrubicina es un f\u00e1rmaco de quimioterapia a base de antraciclinas que act\u00faa intercalando el ADN e inhibiendo la topoisomerasa II. La vincristina es un alcaloide de la vinca que se une a la tubulina e inhibe el ensamblaje de los microt\u00fabulos. La radioterapia es otra opci\u00f3n de tratamiento para los tumores y c\u00e1nceres caninos. La radioterapia act\u00faa da\u00f1ando el ADN de las c\u00e9lulas cancerosas, lo que impide que se dividan. El tipo m\u00e1s com\u00fan de radioterapia utilizada para tratar tumores y c\u00e1nceres caninos es la radioterapia externa. La radioterapia externa es un tipo de radioterapia que utiliza una m\u00e1quina para dirigir haces de alta energ\u00eda a las c\u00e9lulas cancerosas. Existen dos tipos de radioterapia externa: 1. Fototerapia: La fototerapia utiliza rayos X de alta energ\u00eda para destruir las c\u00e9lulas cancerosas. 2. 2. La terapia de protones: La terapia de protones utiliza haces de protones de alta energ\u00eda para destruir las c\u00e9lulas cancerosas. La terapia de protones es m\u00e1s reciente y puede tener menos efectos secundarios que la terapia de fotones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La quimioterapia es un tipo de tratamiento farmacol\u00f3gico que utiliza sustancias qu\u00edmicas para destruir las c\u00e9lulas cancerosas. La quimioterapia puede administrarse por v\u00eda intravenosa (a trav\u00e9s de una vena) o por v\u00eda oral (por la boca). La quimioterapia suele utilizarse en combinaci\u00f3n con otros tratamientos, como la cirug\u00eda o la radioterapia. La quimioterapia suele administrarse en ciclos, cada uno de los cuales consiste en un periodo de tratamiento seguido de un periodo de descanso. La quimioterapia suele asociarse a efectos secundarios, como ca\u00edda del cabello, n\u00e1useas y v\u00f3mitos, y fatiga. La radioterapia es un tipo de terapia que utiliza rayos X de alta energ\u00eda u otras part\u00edculas para destruir las c\u00e9lulas cancerosas. La radioterapia puede administrarse externamente, dirigiendo la radiaci\u00f3n hacia el c\u00e1ncer desde el exterior del cuerpo, o internamente, colocando una sustancia radiactiva en el c\u00e1ncer o cerca de \u00e9l. La radioterapia suele utilizarse en combinaci\u00f3n con otros tratamientos, como la cirug\u00eda o la quimioterapia. La radioterapia suele estar asociada a efectos secundarios, como fatiga, irritaci\u00f3n de la piel y diarrea. La terapia dirigida es un tipo de tratamiento farmacol\u00f3gico que act\u00faa sobre mol\u00e9culas espec\u00edficas implicadas en el crecimiento y la propagaci\u00f3n de las c\u00e9lulas cancerosas. A menudo se utiliza en combinaci\u00f3n con otros tratamientos, como la cirug\u00eda o la quimioterapia. A menudo se asocia a efectos secundarios como fatiga, irritaci\u00f3n cut\u00e1nea y diarrea.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;La inmunoterapia es un tipo de tratamiento farmacol\u00f3gico que utiliza el sistema inmunitario del organismo para destruir las c\u00e9lulas cancerosas. La inmunoterapia puede administrarse por v\u00eda intravenosa (a trav\u00e9s de una vena) o mediante inyecci\u00f3n. La inmunoterapia suele utilizarse en combinaci\u00f3n con otros tratamientos, como la cirug\u00eda, la radioterapia o la quimioterapia. Para que la inmunoterapia sea eficaz, las c\u00e9lulas cancerosas deben tener determinadas prote\u00ednas en su superficie. Tambi\u00e9n es importante saber si estas prote\u00ednas est\u00e1n presentes en las c\u00e9lulas antes de iniciar la inmunoterapia. Existen varios tipos de inmunoterapia, entre los que se incluyen: Anticuerpos monoclonales: Los anticuerpos monoclonales se fabrican en el laboratorio para que se adhieran a prote\u00ednas espec\u00edficas de las c\u00e9lulas cancerosas. Una vez que el anticuerpo se adhiere a la c\u00e9lula cancerosa, puede ayudar al organismo a destruirla. Los anticuerpos monoclonales pueden utilizarse solos o en combinaci\u00f3n con otros tratamientos. Los anticuerpos monoclonales se fabrican en el laboratorio para que se adhieran a prote\u00ednas espec\u00edficas de las c\u00e9lulas cancerosas. Una vez que el anticuerpo se adhiere a la c\u00e9lula cancerosa, puede ayudar al organismo a destruirla. Los anticuerpos monoclonales pueden utilizarse solos o en combinaci\u00f3n con otros tratamientos. Terapia de transferencia de c\u00e9lulas T: La terapia de transferencia de c\u00e9lulas T es un tipo de inmunoterapia que utiliza c\u00e9lulas T (gl\u00f3bulos blancos que combaten las infecciones) para ayudar al organismo a eliminar las c\u00e9lulas cancerosas. En esta terapia, se extraen gl\u00f3bulos blancos del paciente y se env\u00edan al laboratorio. En el laboratorio, las c\u00e9lulas se modifican para que reconozcan y eliminen las c\u00e9lulas cancerosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la autora: La Dra. Faith Whitehead es veterinaria licenciada e investigadora.<\/p>","protected":false},"excerpt":{"rendered":"<p>Drugs are an important part of treating dog tumors and cancers. Without drugs, many treatments would not be possible.&nbsp;Drugs are used to treat the tumor directly, as well as to treat side effects of treatments.&nbsp;Antibiotics are used to treat infections, and anti-nausea drugs are used to prevent and treat nausea and vomiting. Pain medications are [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"1080","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[157,4,159,1],"tags":[209,208],"class_list":["post-1508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cat-cancer-and-tumor","category-dog-cancer-and-tumor","category-medicines-and-therapies","category-research-and-news","tag-dog-tumor-medicine","tag-drugs-for-treating-dog-tumors-and-cancers"],"jetpack_featured_media_url":"https:\/\/www.tcm-vet.com\/wp-content\/uploads\/2022\/11\/YS08.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2782,"url":"https:\/\/www.tcm-vet.com\/es\/what-are-the-benefits-of-cbd-oil-for-canine-tumors-and-cancer\/","url_meta":{"origin":1508,"position":0},"title":"\u00bfCu\u00e1les son los beneficios del aceite de CBD para los tumores y el c\u00e1ncer caninos?","author":"TCMVET","date":"mayo 31, 2023","format":false,"excerpt":"El aceite de CBD ha ganado popularidad como posible tratamiento para diversas afecciones en humanos y animales, incluyendo tumores y c\u00e1ncer canino. Sin embargo, es importante se\u00f1alar que, si bien existen algunos testimonios y se est\u00e1n realizando investigaciones, la evidencia cient\u00edfica sobre el aceite de CBD en particular para el tratamiento de tumores y\u2026","rel":"","context":"En \u00abDog Cancer &amp; Tumors\u00bb","block_context":{"text":"Dog Cancer &amp; Tumors","link":"https:\/\/www.tcm-vet.com\/es\/category\/dog-cancer-and-tumor\/"},"img":{"alt_text":"Exploring the Therapeutic Benefits of CBD Oil for Canine Tumors and Cancer Treatment","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2023\/05\/Exploring-the-Therapeutic-Benefits-of-CBD-Oil-for-Canine-Tumors-and-Cancer-Treatment.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9681,"url":"https:\/\/www.tcm-vet.com\/es\/treatment-options-for-canine-mediastinal-tumors-from-surgery-to-chemotherapy\/","url_meta":{"origin":1508,"position":1},"title":"Opciones de tratamiento para los tumores mediast\u00ednicos caninos: desde la cirug\u00eda hasta la quimioterapia","author":"TCMVET","date":"agosto 29, 2024","format":false,"excerpt":"Los tumores mediast\u00ednicos en perros son graves y a menudo mortales, por lo que requieren un tratamiento integral y personalizado. El mediastino, una cavidad central del t\u00f3rax, alberga \u00f3rganos vitales como el coraz\u00f3n, el es\u00f3fago y los principales vasos sangu\u00edneos. Los tumores en esta zona pueden causar problemas de salud importantes, por lo que un tratamiento precoz y eficaz es fundamental.","rel":"","context":"En \u00abDog Cancer &amp; Tumors\u00bb","block_context":{"text":"Dog Cancer &amp; Tumors","link":"https:\/\/www.tcm-vet.com\/es\/category\/dog-cancer-and-tumor\/"},"img":{"alt_text":"Treatment Options for Canine Mediastinal Tumors: From Surgery to Chemotherapy","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/08\/A_peaceful_and_happy_dog_sitting_or_lying_in_a_sun.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/08\/A_peaceful_and_happy_dog_sitting_or_lying_in_a_sun.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/08\/A_peaceful_and_happy_dog_sitting_or_lying_in_a_sun.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/08\/A_peaceful_and_happy_dog_sitting_or_lying_in_a_sun.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4606,"url":"https:\/\/www.tcm-vet.com\/es\/tigilanol-tiglate-a-breakthrough-treatment-for-dogs-with-tumors\/","url_meta":{"origin":1508,"position":2},"title":"Tigilanol Tiglate: A Breakthrough Treatment for Dogs with Tumors","author":"TCMVET","date":"junio 6, 2024","format":false,"excerpt":"El c\u00e1ncer en los perros es una preocupaci\u00f3n creciente para los due\u00f1os de mascotas.","rel":"","context":"En \u00abMedicines &amp; Therapies\u00bb","block_context":{"text":"Medicines &amp; Therapies","link":"https:\/\/www.tcm-vet.com\/es\/category\/medicines-and-therapies\/"},"img":{"alt_text":"Tigilanol Tiglate\uff1a Tumor Treatment Breakthrough for Dogs","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/06\/Tigilanol-Tiglate-Tumor-Treatment-Breakthrough-for-Dogs.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3604,"url":"https:\/\/www.tcm-vet.com\/es\/treatment-options-for-squamous-cell-carcinoma-in-small-animals\/","url_meta":{"origin":1508,"position":3},"title":"Opciones de tratamiento para el carcinoma de c\u00e9lulas escamosas en animales peque\u00f1os","author":"TCMVET","date":"marzo 7, 2024","format":false,"excerpt":"El carcinoma de c\u00e9lulas escamosas (CCE) es un tipo de c\u00e1ncer prevalente en animales peque\u00f1os, afectando particularmente a perros y gatos.","rel":"","context":"En \u00abCat Cancer &amp; Tumors\u00bb","block_context":{"text":"Cat Cancer &amp; Tumors","link":"https:\/\/www.tcm-vet.com\/es\/category\/cat-cancer-and-tumor\/"},"img":{"alt_text":"cat mouth with dental issues visible","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/03\/2.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8130,"url":"https:\/\/www.tcm-vet.com\/es\/electrochemotherapy-a-cutting-edge-treatment-for-canine-cancer\/","url_meta":{"origin":1508,"position":4},"title":"Electroquimioterapia: un tratamiento de vanguardia para el c\u00e1ncer canino","author":"TCMVET","date":"agosto 1, 2024","format":false,"excerpt":"La electroquimioterapia se perfila como un tratamiento revolucionario para el c\u00e1ncer canino, ofreciendo nuevas esperanzas tanto a due\u00f1os de mascotas como a veterinarios. Esta terapia avanzada combina pulsos el\u00e9ctricos con quimioterapia para potenciar la absorci\u00f3n de f\u00e1rmacos por las c\u00e9lulas cancerosas, logrando as\u00ed un tratamiento oncol\u00f3gico m\u00e1s eficaz y espec\u00edfico. En este art\u00edculo, profundizamos en sus beneficios\u2026","rel":"","context":"En \u00abDog Cancer &amp; Tumors\u00bb","block_context":{"text":"Dog Cancer &amp; Tumors","link":"https:\/\/www.tcm-vet.com\/es\/category\/dog-cancer-and-tumor\/"},"img":{"alt_text":"Revolutionizing Canine Cancer Care The Power of Electrochemotherapy","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/08\/Revolutionizing-Canine-Cancer-Care-The-Power-of-Electrochemotherapy.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/08\/Revolutionizing-Canine-Cancer-Care-The-Power-of-Electrochemotherapy.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/08\/Revolutionizing-Canine-Cancer-Care-The-Power-of-Electrochemotherapy.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/08\/Revolutionizing-Canine-Cancer-Care-The-Power-of-Electrochemotherapy.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7559,"url":"https:\/\/www.tcm-vet.com\/es\/revolutionizing-canine-cancer-care-innovative-strategies-and-treatments-for-your-furry-friend\/","url_meta":{"origin":1508,"position":5},"title":"Revolucionando la atenci\u00f3n del c\u00e1ncer canino: estrategias y tratamientos innovadores para su amigo peludo","author":"TCMVET","date":"julio 25, 2024","format":false,"excerpt":"Al enfrentarse a un diagn\u00f3stico de c\u00e1ncer en su amado perro, encontrar los mejores tratamientos se convierte en una prioridad.","rel":"","context":"En \u00abpet Chinese herbal medicine\u00bb","block_context":{"text":"pet Chinese herbal medicine","link":"https:\/\/www.tcm-vet.com\/es\/category\/pet-chinese-herbal-medicine\/"},"img":{"alt_text":"Cutting-Edge Strategies to Combat Canine Cancer","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/Cutting-Edge-Strategies-to-Combat-Canine-Cancer.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/Cutting-Edge-Strategies-to-Combat-Canine-Cancer.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/Cutting-Edge-Strategies-to-Combat-Canine-Cancer.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/Cutting-Edge-Strategies-to-Combat-Canine-Cancer.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/posts\/1508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/comments?post=1508"}],"version-history":[{"count":0,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/posts\/1508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/media\/1520"}],"wp:attachment":[{"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/media?parent=1508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/categories?post=1508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/tags?post=1508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}