{"id":1526,"date":"2022-11-11T04:16:31","date_gmt":"2022-11-11T04:16:31","guid":{"rendered":"https:\/\/www.tcm-vet.com\/?p=1526"},"modified":"2023-04-15T11:43:22","modified_gmt":"2023-04-15T11:43:22","slug":"ultima-investigacion-sobre-el-cancer-en-perros","status":"publish","type":"post","link":"https:\/\/www.tcm-vet.com\/es\/latest-research-on-dog-cancer\/","title":{"rendered":"\u00daltimas investigaciones sobre el c\u00e1ncer canino"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Se est\u00e1 investigando mucho sobre las causas y el tratamiento del c\u00e1ncer canino. Algunos de los descubrimientos recientes m\u00e1s prometedores son: En primer lugar, un estudio publicado en la revista Carcinogenesis en marzo de 2015 descubri\u00f3 que los perros alimentados con una dieta rica en antioxidantes y \u00e1cidos grasos omega-3 ten\u00edan un menor riesgo de desarrollar c\u00e1ncer. En segundo lugar, un estudio publicado en la revista PLoS One en enero de 2015 descubri\u00f3 que los perros con altos niveles de la enzima lipoxigenasa ten\u00edan m\u00e1s probabilidades de desarrollar c\u00e1ncer. En tercer lugar, un estudio publicado en la revista Nature en septiembre de 2014 descubri\u00f3 que una prote\u00edna llamada SIRT6 protege contra el c\u00e1ncer al impedir que las c\u00e9lulas se dividan. En cuarto lugar, un estudio publicado en la revista Science en junio de 2014 descubri\u00f3 que un f\u00e1rmaco llamado metformina puede ayudar a prevenir el c\u00e1ncer al ralentizar el crecimiento de las c\u00e9lulas cancerosas. Un estudio publicado en la revista Nature en mayo de 2014 descubri\u00f3 que una prote\u00edna llamada p53 ayuda a prevenir el c\u00e1ncer al impedir que las c\u00e9lulas se dividan. Adem\u00e1s, un estudio publicado en la revista Nature en enero de 2014 descubri\u00f3 que una prote\u00edna llamada BRCA1 ayuda a prevenir el c\u00e1ncer reparando el ADN da\u00f1ado. Un estudio publicado en la revista Science en diciembre de 2013 descubri\u00f3 que un f\u00e1rmaco llamado rapamicina puede ayudar a prevenir el c\u00e1ncer al ralentizar el crecimiento de las c\u00e9lulas cancerosas. Por \u00faltimo, un estudio publicado en la revista Nature en octubre de 2013 descubri\u00f3 que una prote\u00edna llamada PTEN ayuda a prevenir el c\u00e1ncer al impedir que las c\u00e9lulas se dividan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3n para la Salud Canina del American Kennel Club est\u00e1 financiando un estudio sobre la gen\u00e9tica de los tumores de mastocitos en perros, que se espera proporcione informaci\u00f3n sobre las causas y los posibles tratamientos de este tipo de c\u00e1ncer. La Fundaci\u00f3n para la Salud Canina tambi\u00e9n financia un estudio sobre la gen\u00e9tica de los mastocitomas en perros. Se espera que este estudio proporcione informaci\u00f3n sobre las causas y los posibles tratamientos de este tipo de c\u00e1ncer. Estas investigaciones han planteado las siguientes hip\u00f3tesis Una posible relaci\u00f3n entre ciertas razas de perros y un mayor riesgo de desarrollar c\u00e1ncer -Una posible relaci\u00f3n entre la esterilizaci\u00f3n temprana y un menor riesgo de desarrollar c\u00e1ncer. Algunas de las \u00faltimas investigaciones sobre el c\u00e1ncer canino incluyen estudios sobre nuevos tratamientos, como la inmunoterapia y la terapia dirigida. Se est\u00e1n llevando a cabo ensayos cl\u00ednicos para muchos de estos nuevos tratamientos, as\u00ed que hable con su veterinario para saber si su perro puede ser un buen candidato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un estudio publicado en 2019 en el Journal of the American Veterinary Medical Association descubri\u00f3 que la inmunoterapia, tambi\u00e9n conocida como terapia biol\u00f3gica, se asoci\u00f3 con un aumento significativo en el tiempo de supervivencia de los perros con linfoma. El estudio analiz\u00f3 los datos de 2.200 perros con linfoma tratados en 24 centros de oncolog\u00eda veterinaria. La mediana del tiempo de supervivencia de los perros que recibieron inmunoterapia fue de 386 d\u00edas, en comparaci\u00f3n con 172 d\u00edas para los perros que no recibieron inmunoterapia. Otro estudio publicado en 2020 en la revista Journal of Veterinary Internal Medicine examin\u00f3 el uso de la inmunoterapia para perros con osteosarcoma. El estudio descubri\u00f3 que la inmunoterapia aumentaba el tiempo de supervivencia de los perros con osteosarcoma y tambi\u00e9n mejoraba la calidad de vida. La mediana del tiempo de supervivencia para los perros que recibieron inmunoterapia fue de 365 d\u00edas, en comparaci\u00f3n con 240 d\u00edas para los perros que no recibieron inmunoterapia. Por \u00faltimo, un estudio publicado en 2019 en la revista Cancer Cell analiz\u00f3 el uso de un f\u00e1rmaco de terapia dirigida llamado fosfato de toceranib (Palladia) para el tratamiento de perros con mastocitomas. El estudio encontr\u00f3 que el fosfato de toceranib se asoci\u00f3 con un aumento significativo en el tiempo de supervivencia de los perros con tumores de mastocitos. La mediana de supervivencia de los perros que recibieron fosfato de toceranib fue de 365 d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las \u00faltimas investigaciones indican que un nuevo tratamiento para el c\u00e1ncer canino, llamado inmunoterapia, est\u00e1 dando resultados prometedores. El tratamiento utiliza el propio sistema inmunitario del perro para combatir el c\u00e1ncer. Un nuevo f\u00e1rmaco llamado Palladia se muestra prometedor como tratamiento del c\u00e1ncer canino. Palladia se dirige a una prote\u00edna espec\u00edfica de las c\u00e9lulas cancerosas, y se ha demostrado que mata las c\u00e9lulas cancerosas en los perros. Palladia se est\u00e1 probando actualmente en ensayos cl\u00ednicos y a\u00fan no est\u00e1 disponible para uso general. Sin embargo, es posible que se apruebe su uso en el futuro. Palladia no es el \u00fanico f\u00e1rmaco inmunoter\u00e1pico prometedor como tratamiento del c\u00e1ncer canino. Otro f\u00e1rmaco de inmunoterapia, llamado toceranib, tambi\u00e9n se est\u00e1 probando en ensayos cl\u00ednicos. El toceranib se dirige a una prote\u00edna diferente que es espec\u00edfica de las c\u00e9lulas cancerosas, y tambi\u00e9n ha demostrado eliminar c\u00e9lulas cancerosas en perros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la autora: La Dra. Faith Whitehead es veterinaria licenciada e investigadora.<\/p>","protected":false},"excerpt":{"rendered":"<p>There is a great deal of ongoing research into the causes and treatment of dog cancer. Some of the most promising recent discoveries include:&nbsp;Firstly, a study published in the journal Carcinogenesis in March 2015 found that dogs fed a diet high in antioxidants and omega-3 fatty acids had a lower risk of developing cancer. Secondly, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"1080","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,159,1],"tags":[221],"class_list":["post-1526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dog-cancer-and-tumor","category-medicines-and-therapies","category-research-and-news","tag-latest-research-on-dog-cancer"],"jetpack_featured_media_url":"https:\/\/www.tcm-vet.com\/wp-content\/uploads\/2022\/11\/YS20.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6504,"url":"https:\/\/www.tcm-vet.com\/es\/exploring-the-link-between-dietary-patterns-and-canine-cancer-risk\/","url_meta":{"origin":1526,"position":0},"title":"Explorando el v\u00ednculo entre los patrones diet\u00e9ticos y el riesgo de c\u00e1ncer canino","author":"TCMVET","date":"julio 13, 2024","format":false,"excerpt":"A medida que los due\u00f1os de mascotas son cada vez m\u00e1s conscientes de la importancia de la nutrici\u00f3n en el mantenimiento de la salud de sus perros, el papel de los patrones diet\u00e9ticos en la prevenci\u00f3n y el manejo del c\u00e1ncer canino est\u00e1 ganando atenci\u00f3n.","rel":"","context":"En \u00abFood &amp; Health\u00bb","block_context":{"text":"Food &amp; Health","link":"https:\/\/www.tcm-vet.com\/es\/category\/food-and-health\/"},"img":{"alt_text":"How Dietary Choices Influence Canine Cancer Risk","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/How-Dietary-Choices-Influence-Canine-Cancer-Risk.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/How-Dietary-Choices-Influence-Canine-Cancer-Risk.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/How-Dietary-Choices-Influence-Canine-Cancer-Risk.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/How-Dietary-Choices-Influence-Canine-Cancer-Risk.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6501,"url":"https:\/\/www.tcm-vet.com\/es\/blood-sugar-dynamics-in-canine-cancer-patients\/","url_meta":{"origin":1526,"position":1},"title":"Din\u00e1mica del az\u00facar en sangre en pacientes caninos con c\u00e1ncer","author":"TCMVET","date":"julio 13, 2024","format":false,"excerpt":"El c\u00e1ncer en los perros es una enfermedad compleja y multifac\u00e9tica que afecta varios procesos fisiol\u00f3gicos, incluida la regulaci\u00f3n del az\u00facar en la sangre.","rel":"","context":"En \u00abDog Cancer &amp; Tumors\u00bb","block_context":{"text":"Dog Cancer &amp; Tumors","link":"https:\/\/www.tcm-vet.com\/es\/category\/dog-cancer-and-tumor\/"},"img":{"alt_text":"Blood Sugar Dynamics in Canine Cancer Warriors","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/Blood-Sugar-Dynamics-in-Canine-Cancer-Warriors.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/Blood-Sugar-Dynamics-in-Canine-Cancer-Warriors.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/Blood-Sugar-Dynamics-in-Canine-Cancer-Warriors.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/Blood-Sugar-Dynamics-in-Canine-Cancer-Warriors.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6497,"url":"https:\/\/www.tcm-vet.com\/es\/hormone-therapy-and-its-impact-on-canine-cancer-progression\/","url_meta":{"origin":1526,"position":2},"title":"La terapia hormonal y su impacto en la progresi\u00f3n del c\u00e1ncer canino","author":"TCMVET","date":"julio 13, 2024","format":false,"excerpt":"En los \u00faltimos a\u00f1os, la medicina veterinaria ha logrado avances significativos en la comprensi\u00f3n y el tratamiento del c\u00e1ncer en perros. Entre los diversos tratamientos disponibles, la terapia hormonal se ha consolidado como una opci\u00f3n prometedora. Este art\u00edculo explora el impacto potencial de la terapia hormonal en la progresi\u00f3n del c\u00e1ncer canino, destacando sus beneficios, desaf\u00edos y las investigaciones m\u00e1s recientes.","rel":"","context":"En \u00abFood &amp; Health\u00bb","block_context":{"text":"Food &amp; Health","link":"https:\/\/www.tcm-vet.com\/es\/category\/food-and-health\/"},"img":{"alt_text":"The Revolutionary Role of Hormone Therapy in Canine Cancer Control","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/The-Revolutionary-Role-of-Hormone-Therapy-in-Canine-Cancer-Control.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/The-Revolutionary-Role-of-Hormone-Therapy-in-Canine-Cancer-Control.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/The-Revolutionary-Role-of-Hormone-Therapy-in-Canine-Cancer-Control.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/07\/The-Revolutionary-Role-of-Hormone-Therapy-in-Canine-Cancer-Control.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9903,"url":"https:\/\/www.tcm-vet.com\/es\/maintaining-a-healthy-weight-a-key-factor-in-cancer-prevention-for-dogs\/","url_meta":{"origin":1526,"position":3},"title":"Mantener un peso saludable: un factor clave en la prevenci\u00f3n del c\u00e1ncer canino","author":"TCMVET","date":"septiembre 10, 2024","format":false,"excerpt":"Mantener a tu perro en un peso saludable es m\u00e1s que solo movilidad y bienestar general; tambi\u00e9n es un aspecto crucial de la prevenci\u00f3n del c\u00e1ncer.","rel":"","context":"En \u00abDog Cancer &amp; Tumors\u00bb","block_context":{"text":"Dog Cancer &amp; Tumors","link":"https:\/\/www.tcm-vet.com\/es\/category\/dog-cancer-and-tumor\/"},"img":{"alt_text":"Maintaining a Healthy Weight: A Key Factor in Cancer Prevention for Dogs","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/09\/active_dog_weight_article.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/09\/active_dog_weight_article.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/09\/active_dog_weight_article.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/09\/active_dog_weight_article.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9900,"url":"https:\/\/www.tcm-vet.com\/es\/exploring-the-benefits-of-cbd-for-dogs-with-cancer-a-natural-aid-in-therapy\/","url_meta":{"origin":1526,"position":4},"title":"Explorando los beneficios del CBD para perros con c\u00e1ncer: una ayuda natural en la terapia","author":"TCMVET","date":"septiembre 10, 2024","format":false,"excerpt":"A medida que los due\u00f1os de mascotas buscan maneras de mejorar la salud de sus perros, especialmente ante diagn\u00f3sticos dif\u00edciles como el c\u00e1ncer, el CBD (cannabidiol) se perfila como una potente opci\u00f3n natural. Derivado de la planta de cannabis, el CBD no es psicoactivo y ha sido ampliamente estudiado por su potencial para favorecer la salud canina. Si bien\u2026","rel":"","context":"En \u00abMedicines &amp; Therapies\u00bb","block_context":{"text":"Medicines &amp; Therapies","link":"https:\/\/www.tcm-vet.com\/es\/category\/medicines-and-therapies\/"},"img":{"alt_text":"Exploring the Benefits of CBD for Dogs with Cancer: A Natural Aid in Therapy","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/09\/relaxed_dog_cbd_article.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/09\/relaxed_dog_cbd_article.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/09\/relaxed_dog_cbd_article.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2024\/09\/relaxed_dog_cbd_article.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19921,"url":"https:\/\/www.tcm-vet.com\/es\/lack-of-scientific-evidence-the-controversy-and-promise-of-herbal-medicine-in-pet-cancer-treatment\/","url_meta":{"origin":1526,"position":5},"title":"\u00bfFalta de evidencia cient\u00edfica? La controversia y la promesa de la medicina herbaria en el tratamiento del c\u00e1ncer en mascotas.","author":"TCMVET","date":"junio 21, 2025","format":false,"excerpt":"A medida que los due\u00f1os de mascotas buscan alternativas m\u00e1s suaves a los tratamientos convencionales contra el c\u00e1ncer como la quimioterapia y la radiaci\u00f3n, las hierbas chinas tradicionales (TCM) y otros bot\u00e1nicos han aumentado en popularidad.","rel":"","context":"En \u00abpet Chinese herbal medicine\u00bb","block_context":{"text":"pet Chinese herbal medicine","link":"https:\/\/www.tcm-vet.com\/es\/category\/pet-chinese-herbal-medicine\/"},"img":{"alt_text":"Canine Cancer: Is It Contagious? What Multi-Dog Households Should Know","src":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2025\/02\/DALL%C2%B7E-2025-02-06-11.38.07-A-simple-cartoon-style-illustration-of-a-few-dogs-sitting-together-looking-calm-and-friendly.-The-drawing-should-be-minimalistic-and-cute-with-no-ba.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2025\/02\/DALL%C2%B7E-2025-02-06-11.38.07-A-simple-cartoon-style-illustration-of-a-few-dogs-sitting-together-looking-calm-and-friendly.-The-drawing-should-be-minimalistic-and-cute-with-no-ba.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2025\/02\/DALL%C2%B7E-2025-02-06-11.38.07-A-simple-cartoon-style-illustration-of-a-few-dogs-sitting-together-looking-calm-and-friendly.-The-drawing-should-be-minimalistic-and-cute-with-no-ba.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.tcm-vet.com\/wp-content\/uploads\/2025\/02\/DALL%C2%B7E-2025-02-06-11.38.07-A-simple-cartoon-style-illustration-of-a-few-dogs-sitting-together-looking-calm-and-friendly.-The-drawing-should-be-minimalistic-and-cute-with-no-ba.webp?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/posts\/1526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/comments?post=1526"}],"version-history":[{"count":0,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/posts\/1526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/media\/1582"}],"wp:attachment":[{"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/media?parent=1526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/categories?post=1526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tcm-vet.com\/es\/wp-json\/wp\/v2\/tags?post=1526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}